{"id":125,"date":"2025-09-24T10:46:32","date_gmt":"2025-09-24T14:46:32","guid":{"rendered":"https:\/\/lacale.portquebec.ca\/accueil\/"},"modified":"2026-06-11T15:53:18","modified_gmt":"2026-06-11T19:53:18","slug":"homepage","status":"publish","type":"page","link":"https:\/\/lacale.portquebec.ca\/en\/","title":{"rendered":"Homepage"},"content":{"rendered":"\t<div class=\"item component-block-image-full-width has-wave--in-block\">\n\t\t<div class=\"block-image-full-width wave wave--in-block wave--flipped wave--1 wave--color-1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"800\" src=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74.webp\" class=\"attachment-mw_3000 size-mw_3000\" alt=\"Image of an inflatable pink flamingo\" srcset=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74.webp 1920w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-300x125.webp 300w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1024x427.webp 1024w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-768x320.webp 768w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1536x640.webp 1536w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1400x583.webp 1400w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-800x333.webp 800w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1488x620.webp 1488w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1600x667.webp 1600w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1440x600.webp 1440w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1184x493.webp 1184w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-1194x498.webp 1194w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-790x329.webp 790w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-770x321.webp 770w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-562x234.webp 562w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-160x67.webp 160w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_74-320x133.webp 320w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n\t\t<\/div>\n\t<\/div>\n\n\n\t<div class=\"item component-block-text-two-col background-color--1 wave wave--1 wave--color-1\">\n\t\t<div class=\"container block-text-two-col\">\n\t\t\t<div class=\"block-text-two-col__left\">\n\t\t\t\t<div class=\"wysiwyg\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Welcome to La Cale du Port de Qu\u00e9bec<\/h1>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"block-text-two-col__right\">\n\t\t\t\t<div class=\"wysiwyg\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Relaxation \u2013 River view \u2013 Terrace<\/h2>\n<p>Looking for things to do this summer in Quebec City? La Cale du Port de Qu\u00e9bec invites you to the most beautiful terrace in the heart of Old Quebec! Located on the banks of the St. Lawrence River, La Cale du Port de Qu\u00e9bec is a true seaside resort, a gathering place for families to enjoy the pleasures of summer. There are relaxation areas where you can have a drink and a bite to eat while admiring the exceptional view of the river.<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\t<div class=\"item component-block-text-image-no-container background-color--2 wave wave--2 wave--color-2\">\n\t\t<div class=\"component-block-text-image-no-container__container\">\n\t\t\t<div class=\"block-text-image-no-container block-text-image-no-container--is-reverse\">\n\t\t\t\t<div class=\"block-text-image-no-container__content container container--full\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"h2\">Opening May 22, 2026<\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wysiwyg\">\n\t\t\t\t\t\t\t<p data-renderer-start-pos=\"92\">La Cale du Port de Qu\u00e9bec is open from June to September. Admission to the site is free. We look forward to welcoming you this summer!<\/p>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lacale.portquebec.ca\/en\/opening-hours\/\" class=\"button button--primary\">\n\t\t\t\t\t\t\tLearn more\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"block-image-text-no-container__image\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"block-image-text-no-container__image__container\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"759\" height=\"486\" src=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/group.webp\" class=\"attachment-1440_1008 size-1440_1008\" alt=\"Illustration of an inflatable pink flamingo with a wooden chair on the left\" srcset=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/group.webp 759w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/group-300x192.webp 300w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/group-562x360.webp 562w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/group-160x102.webp 160w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/group-320x205.webp 320w\" sizes=\"auto, (max-width: 759px) 100vw, 759px\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\t<div class=\"item component-block-text-image background-color--3 wave wave--1 wave--color-3\">\n\t\t<div class=\"component-block-text-image__container\">\n\t\t\t<div class=\"container\">\n\t\t\t\t<div class=\"block-text-image \">\n\t\t\t\t\t<div class=\"block-text-image__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"h2\">RELAXATION \u2013 RIVER VIEW \u2013 TERRACE<\/h2>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wysiwyg\">\n\t\t\t\t\t\t\t\t<p>Want to enjoy a beer or cocktail on one of Old Quebec&#8217;s most beautiful terraces? Looking for a nice place to eat or enjoy happy hour? Whether with family, friends, or even your coworkers, La Cale du Port de Qu\u00e9bec is the perfect place to relax, eat, and drink in good company.<\/p>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lacale.portquebec.ca\/en\/eat-and-drink\/\" class=\"button button--primary\">\n\t\t\t\t\t\t\t\tView menu\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"block-image-text__image\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"block-image-text__image__container wave-full--left_icon \">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"789\" src=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1184x789.webp\" class=\"attachment-1184_1338 size-1184_1338\" alt=\"Image of people with their feet in the water while enjoying a drink\" srcset=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1184x789.webp 1184w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-300x200.webp 300w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1024x683.webp 1024w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-768x512.webp 768w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1536x1024.webp 1536w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-2048x1366.webp 2048w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1400x934.webp 1400w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-800x533.webp 800w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1488x992.webp 1488w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1600x1067.webp 1600w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1440x960.webp 1440w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-1194x796.webp 1194w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-790x527.webp 790w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-770x513.webp 770w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-562x375.webp 562w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-160x107.webp 160w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_75-320x213.webp 320w\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\t<div class=\"item component-block-image-full-width \">\n\t\t<div class=\"block-image-full-width \">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"800\" src=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76.webp\" class=\"attachment-mw_3000 size-mw_3000\" alt=\"View of La cale du port de Qu\u00e9bec\" srcset=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76.webp 1920w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-300x125.webp 300w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1024x427.webp 1024w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-768x320.webp 768w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1536x640.webp 1536w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1400x583.webp 1400w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-800x333.webp 800w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1488x620.webp 1488w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1600x667.webp 1600w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1440x600.webp 1440w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1184x493.webp 1184w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-1194x498.webp 1194w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-790x329.webp 790w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-770x321.webp 770w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-562x234.webp 562w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-160x67.webp 160w, https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/image_76-320x133.webp 320w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-125","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Homepage - La Cale du Port de Qu\u00e9bec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacale.portquebec.ca\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homepage - La Cale du Port de Qu\u00e9bec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacale.portquebec.ca\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cale du Port de Qu\u00e9bec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lacaleduportdequebec\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T19:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/DJI_0164-2.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/\",\"url\":\"https:\/\/lacale.portquebec.ca\/en\/\",\"name\":\"Homepage - La Cale du Port de Qu\u00e9bec\",\"isPartOf\":{\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#website\"},\"datePublished\":\"2025-09-24T14:46:32+00:00\",\"dateModified\":\"2026-06-11T19:53:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lacale.portquebec.ca\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lacale.portquebec.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#website\",\"url\":\"https:\/\/lacale.portquebec.ca\/en\/\",\"name\":\"La Cale du Port de Qu\u00e9bec\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lacale.portquebec.ca\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#organization\",\"name\":\"La Cale du Port de Qu\u00e9bec\",\"url\":\"https:\/\/lacale.portquebec.ca\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"La Cale du Port de Qu\u00e9bec\"},\"image\":{\"@id\":\"https:\/\/lacale.portquebec.ca\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lacaleduportdequebec\",\"https:\/\/www.instagram.com\/lacaleduportdequebec\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homepage - La Cale du Port de Qu\u00e9bec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacale.portquebec.ca\/en\/","og_locale":"en_US","og_type":"article","og_title":"Homepage - La Cale du Port de Qu\u00e9bec","og_url":"https:\/\/lacale.portquebec.ca\/en\/","og_site_name":"La Cale du Port de Qu\u00e9bec","article_publisher":"https:\/\/www.facebook.com\/lacaleduportdequebec","article_modified_time":"2026-06-11T19:53:18+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/lacale.portquebec.ca\/wp-content\/uploads\/2025\/10\/DJI_0164-2.jpg.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lacale.portquebec.ca\/en\/","url":"https:\/\/lacale.portquebec.ca\/en\/","name":"Homepage - La Cale du Port de Qu\u00e9bec","isPartOf":{"@id":"https:\/\/lacale.portquebec.ca\/en\/#website"},"datePublished":"2025-09-24T14:46:32+00:00","dateModified":"2026-06-11T19:53:18+00:00","breadcrumb":{"@id":"https:\/\/lacale.portquebec.ca\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lacale.portquebec.ca\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lacale.portquebec.ca\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lacale.portquebec.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/lacale.portquebec.ca\/en\/#website","url":"https:\/\/lacale.portquebec.ca\/en\/","name":"La Cale du Port de Qu\u00e9bec","description":"","publisher":{"@id":"https:\/\/lacale.portquebec.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacale.portquebec.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lacale.portquebec.ca\/en\/#organization","name":"La Cale du Port de Qu\u00e9bec","url":"https:\/\/lacale.portquebec.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lacale.portquebec.ca\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"La Cale du Port de Qu\u00e9bec"},"image":{"@id":"https:\/\/lacale.portquebec.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lacaleduportdequebec","https:\/\/www.instagram.com\/lacaleduportdequebec\/"]}]}},"_links":{"self":[{"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/pages\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":21,"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/pages\/125\/revisions"}],"predecessor-version":[{"id":1559,"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/pages\/125\/revisions\/1559"}],"wp:attachment":[{"href":"https:\/\/lacale.portquebec.ca\/en\/wp-json\/wp\/v2\/media?parent=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}